{"id":10156,"date":"2026-07-30T09:59:48","date_gmt":"2026-07-30T09:59:48","guid":{"rendered":"https:\/\/flexlifting.girafdev.com\/product\/atlas-1te3l-vollelektrischer-kran-mit-3-fach-teleskop-ausschub-1000-kg\/"},"modified":"2026-09-02T12:42:18","modified_gmt":"2026-09-02T12:42:18","slug":"atlas-1te3l-vollelektrischer-kran-mit-3-fach-teleskop-ausschub-1000-kg","status":"publish","type":"product","link":"https:\/\/flexlifting.girafdev.com\/de\/product\/atlas-1te3l-vollelektrischer-kran-mit-3-fach-teleskop-ausschub-1000-kg\/","title":{"rendered":"ATLAS 1TE3L ELEKTROKRAN MIT GEGENGEWICHT"},"content":{"rendered":"<p><b>Der ATLAS 1TE3L ist ein<\/b>\u00a0<b>vollelektrischer Pick &amp; Carry-Kran<\/b>\u00a0mit einer Traglast von 1 Tonne und\u00a0<b>Ausladung \u00fcber 3 Meter<\/b>. ATLAS 1TE3L ist ein Kran mit H\u00f6chstleistungen und ist mit 3-Fach-Teleskop Ausschub ausgestattet.<\/p>\n<p>Eines der Hauptmerkmale dieses Pick &amp; Carry Krans ist, dass keine seitlichen Abst\u00fctzungen erforderlich sind und ist mit der Last verfahrbar.<\/p>\n<p>Beim ATLAS 1TE3L handelt es sich um den kleinsten Kran seiner Kategorie, der besonders gut zu steuern ist und somit jeden Ort erreichen kann, um die Last aufzunehmen. Er hat einen sehr kleinen Wendekreis, sodass er auch in G\u00e4ngen mit engen Biegungen und Kurven entlangfahren kann. In engen R\u00e4umen kann er sich um die eigene Achse drehen.<\/p>\n<p>Das Anheben, Absenken, Ausfahren und Einfahren des Auslegers erfolgt elektrisch. Alle Bewegungen k\u00f6nnen vom Bediener \u00fcber Steuerhebel am Kranbedienfeld gesteuert werden.\u00a0<b>Geschwindigkeit und Proportionalit\u00e4t werden durch die Bewegung der Hebel gesteuert<\/b>.<\/p>\n<p>Standardausstattung: wartungsfreie, versiegelte AGM-Batterien, externes Batterieladeger\u00e4t, Leuchts\u00e4ule zur Anzeige der ordnungsgem\u00e4\u00dfen Funktion des Krans und \u00dcberlastwarnung, Not-Aus. Der ATLAS 1TE3L -Kran verf\u00fcgt au\u00dferdem \u00fcber ein Multifunktionsdisplay, das Ladezustand, Batteriespannung und Betriebsstunden anzeigt.<\/p>\n<p><b>Sicherheitsmerkmale:<\/b><\/p>\n<p><b>Dynamischer Lastbegrenzer<\/b>, der \u00dcberlastungen und m\u00f6gliche Unf\u00e4lle verhindert. Es \u00fcberwacht kontinuierlich die angehobene oder gehandhabte Last und begrenzt den Betrieb automatisch, wenn die Last den vorgegebenen Sicherheitsgrenzwert \u00fcberschreitet.<\/p>\n<p>Bei einem Bruch des Hydraulikschlauchs wird automatisch ein\u00a0<b>Sperrventil<\/b>\u00a0aktiviert, das ein unkontrolliertes Absinken der Last verhindert.<\/p>\n<p>Die Deichsel ist mit einem Geschwindigkeitsw\u00e4hler ausgestattet, der eine Anpassung der Fahrzeuggeschwindigkeit an unterschiedliche Betriebsanforderungen erm\u00f6glicht. Es stehen zwei Positionen zur Verf\u00fcgung:<\/p>\n<ul>\n<li>Langsamer Modus: Begrenzt die H\u00f6chstgeschwindigkeit auf 1,5 km\/h, ideal f\u00fcr pr\u00e4zises Man\u00f6vrieren auf engstem Raum und schonende Handhabung von Lasten.<\/li>\n<li>Standardgeschwindigkeit: Erm\u00f6glicht eine H\u00f6chstgeschwindigkeit von 3 km\/h, geeignet f\u00fcr Langstreckenfahrten unter Standardbedingungen<\/li>\n<\/ul>\n<p>ATLAS 1TE3L kann mit jeder Art von Hebezubeh\u00f6r f\u00fcr spezifische Anwendungen ausgestattet werden: Hebesauger, Hebebalken, Klemmen, Kippvorrichtungen, Permanentmagnete usw.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>MIT BEDIENHEBELN<\/p>\n<p>TRAGKRAFT\u00a01000 KG<\/p>\n","protected":false},"featured_media":10144,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[851],"product_tag":[],"class_list":["post-10156","product","type-product","status-publish","has-post-thumbnail","product_cat-pick-carry-krane-mit-doppel-oder-3-fach-teleskop-ausschub","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10156","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/comments?post=10156"}],"version-history":[{"count":2,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10156\/revisions"}],"predecessor-version":[{"id":10191,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10156\/revisions\/10191"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/media\/10144"}],"wp:attachment":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/media?parent=10156"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_brand?post=10156"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_cat?post=10156"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_tag?post=10156"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}