{"id":10225,"date":"2026-07-30T12:35:34","date_gmt":"2026-07-30T12:35:34","guid":{"rendered":"https:\/\/flexlifting.girafdev.com\/product\/mobilkran-vollelektrisch-orbit500-traglast-500-kg\/"},"modified":"2026-09-02T12:50:01","modified_gmt":"2026-09-02T12:50:01","slug":"mobilkran-vollelektrisch-orbit500-traglast-500-kg","status":"publish","type":"product","link":"https:\/\/flexlifting.girafdev.com\/de\/product\/mobilkran-vollelektrisch-orbit500-traglast-500-kg\/","title":{"rendered":"ORBIT 500EL ELEKTRISCHER SCHWENKKRAN"},"content":{"rendered":"<p><b>Der ORBIT 500EL-Kran ist ein vollelektrischer Schwenkkran, der das Heben von Lasten bis zu 500 kg erm\u00f6glicht.<\/b><\/p>\n<p>Dieses\u00a0<b>mobile Hebeger\u00e4t<\/b>\u00a0ist standardm\u00e4\u00dfig mit einem doppelten elektrischen Ausschub ausgestattet, der eine Ausladung von 2410 mm erm\u00f6glicht, und einem lenkbaren Motorrad, das auch in Arbeitsumgebungen mit begrenztem Platzangebot optimale Man\u00f6vrierf\u00e4higkeit bietet.<\/p>\n<p><b>Das Steuerhebelsystem erm\u00f6glicht es dem Bediener, die Bewegungen des Teleskoparms mit \u00e4u\u00dferster Pr\u00e4zision und Fl\u00fcssigkeit zu steuern. Die Geschwindigkeit jeder Armbewegung ist perfekt modulierbar und gew\u00e4hrleistet so eine pr\u00e4zise Positionierung der Last an jedem Punkt im Aktionsbereich. Die motorisierte Drehung vervollst\u00e4ndigt die Vielseitigkeit dieses Krans und macht ihn ideal f\u00fcr Hebearbeiten auf engstem Raum.<\/b><\/p>\n<p>Der\u00a0<b>motorisierte Kran ORBIT 500EL<\/b>\u00a0ist eine All-in-One-<b>Hebel\u00f6sung<\/b>, die dank seiner\u00a0<b>210 \u00b0-Drehung und des Teleskoparms<\/b>\u00a0alle Vorg\u00e4nge zum Be- und Entladen von Formen, zur Best\u00fcckung von CNC-Bearbeitungszentren und zur Positionierung von Blechen auf Plasmaschneidemaschinen vereinfacht und optimiert, Wartung und Montage von Komponenten an verschiedenen Maschinentypen.<\/p>\n<p><b>Der elektrohydraulische Kran Orbit 500EL ist die ideale L\u00f6sung f\u00fcr alle, die maximale Man\u00f6vrierf\u00e4higkeit auf engstem Raum ben\u00f6tigen. Seine begrenzte Breite von 990 mm und die Drehung des Arm-Ballast-Systems ohne zus\u00e4tzliches Volumen machen ihn einzigartig in seiner Art.<\/b><\/p>\n<p>Der\u00a0<b>elektrohydraulische Kran ORBIT 500EL<\/b>\u00a0ist mit Hebelsteuerungen ausgestattet, um die folgenden Funktionen mit einstellbarer und proportionaler Geschwindigkeit zu aktivieren: Heben, Senken, Ausfahren, Einfahren und Drehen des Arms.<\/p>\n<p>Serienm\u00e4\u00dfige Ausstattung: versiegelte und wartungsfreie AGM-Batterien, externes Batterieladeger\u00e4t, LED-Leuchtanzeige f\u00fcr ordnungsgem\u00e4\u00dfen Betrieb und \u00dcberlastung, Not-Aus-Taste. Der ORBIT 500EL-Kran ist au\u00dferdem mit einem Multifunktionsdisplay ausgestattet, das den Ladezustand, die Batteriespannung und die Betriebsstunden anzeigt.<\/p>\n<p><b>Sicherheitsfunktionen:<\/b><\/p>\n<p><b>Dynamischer Lastbegrenzer<\/b>, der \u00dcberlastungen und m\u00f6gliche Unf\u00e4lle verhindert. Es \u00fcberwacht st\u00e4ndig die angehobene oder bewegte Last und begrenzt den Vorgang automatisch, wenn die Last den voreingestellten Sicherheitsgrenzwert \u00fcberschreitet.<\/p>\n<p>Bei einem Bruch in den Leitungen des Hydrauliksystems wird automatisch ein\u00a0<b>Absperrventil\u00a0<\/b>aktiviert, das ein unkontrolliertes Absinken der Last verhindert.<\/p>\n<p>Am Steuerstand befindet sich ein Geschwindigkeitsw\u00e4hler, mit dem Sie die Geschwindigkeit des Fahrzeugs an unterschiedliche Einsatzanforderungen anpassen k\u00f6nnen.<\/p>\n<ul>\n<li>Langsamer Modus: Begrenzt die H\u00f6chstgeschwindigkeit auf 1,5 km\/h, ideal f\u00fcr pr\u00e4zise Man\u00f6ver auf engstem Raum und empfindliche Handhabung von Lasten.<\/li>\n<li>Standardgeschwindigkeit: Erm\u00f6glicht eine H\u00f6chstgeschwindigkeit von 3 km\/h, geeignet f\u00fcr lange Strecken unter Standardbedingungen<\/li>\n<\/ul>\n","protected":false},"excerpt":{"rendered":"<p>  MIT BEDIENHEBELN <\/p>\n<p> TRAGKRAFT\u00a0500 KG  <\/p>\n","protected":false},"featured_media":10203,"comment_status":"open","ping_status":"closed","template":"","meta":{"_acf_changed":false},"product_brand":[],"product_cat":[851],"product_tag":[],"class_list":["post-10225","product","type-product","status-publish","has-post-thumbnail","product_cat-pick-carry-krane-mit-doppel-oder-3-fach-teleskop-ausschub","first","instock","shipping-taxable","product-type-simple"],"acf":[],"_links":{"self":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10225","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product"}],"about":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/types\/product"}],"replies":[{"embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/comments?post=10225"}],"version-history":[{"count":2,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10225\/revisions"}],"predecessor-version":[{"id":10247,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product\/10225\/revisions\/10247"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/media\/10203"}],"wp:attachment":[{"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/media?parent=10225"}],"wp:term":[{"taxonomy":"product_brand","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_brand?post=10225"},{"taxonomy":"product_cat","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_cat?post=10225"},{"taxonomy":"product_tag","embeddable":true,"href":"https:\/\/flexlifting.girafdev.com\/de\/wp-json\/wp\/v2\/product_tag?post=10225"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}